{"id":24,"count":11,"description":"","link":"https:\/\/dev-dgrtechlabs.co\/craven\/category\/designs\/","name":"Designs","slug":"designs","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Designs Archives - Ksenia Craven<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Designs Archives - Ksenia Craven\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev-dgrtechlabs.co\/craven\/category\/designs\/\" \/>\n<meta property=\"og:site_name\" content=\"Ksenia Craven\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Designs Archives - Ksenia Craven","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Designs Archives - Ksenia Craven","og_url":"https:\/\/dev-dgrtechlabs.co\/craven\/category\/designs\/","og_site_name":"Ksenia Craven","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/dev-dgrtechlabs.co\/craven\/category\/designs\/","url":"https:\/\/dev-dgrtechlabs.co\/craven\/category\/designs\/","name":"Designs Archives - Ksenia Craven","isPartOf":{"@id":"https:\/\/dev-dgrtechlabs.co\/craven\/#website"},"breadcrumb":{"@id":"https:\/\/dev-dgrtechlabs.co\/craven\/category\/designs\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/dev-dgrtechlabs.co\/craven\/category\/designs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev-dgrtechlabs.co\/craven\/"},{"@type":"ListItem","position":2,"name":"Designs"}]},{"@type":"WebSite","@id":"https:\/\/dev-dgrtechlabs.co\/craven\/#website","url":"https:\/\/dev-dgrtechlabs.co\/craven\/","name":"Ksenia Craven","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev-dgrtechlabs.co\/craven\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/dev-dgrtechlabs.co\/craven\/wp-json\/wp\/v2\/categories\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev-dgrtechlabs.co\/craven\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/dev-dgrtechlabs.co\/craven\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/dev-dgrtechlabs.co\/craven\/wp-json\/wp\/v2\/posts?categories=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}